{"id":9292,"date":"2019-03-22T16:52:35","date_gmt":"2019-03-22T15:52:35","guid":{"rendered":"https:\/\/www.aphyllanthe.fr\/association\/?p=9292"},"modified":"2019-03-22T18:01:05","modified_gmt":"2019-03-22T17:01:05","slug":"assemblee-generale-2019","status":"publish","type":"post","link":"https:\/\/www.aphyllanthe.fr\/association\/assemblee-generale-2019\/","title":{"rendered":"Assembl\u00e9e G\u00e9n\u00e9rale 2019"},"content":{"rendered":"<p>L\u2019Assembl\u00e9e G\u00e9n\u00e9rale Annuelle  de l&rsquo;Association l\u2019Aphyllanthe s\u2019est d\u00e9roul\u00e9e le vendredi 15 mars \u00e0 18H30 \u00e0 la salle polyvalente de Foissac en pr\u00e9sence d&rsquo;une soixantaine d&rsquo;adh\u00e9rents. <!--more--><\/p>\n<p>En plus de son AGO, l\u2019association a organis\u00e9 une AG Extraordinaire pour voter une modification des statuts. Cette modification visait surtout la mise en conformit\u00e9 des statuts (dont les originaux dataient de 2003) avec la situation en 2019. Apr\u00e8s une br\u00e8ve discussion, l\u2019assembl\u00e9e a approuv\u00e9 les <a href=\"http:\/\/www.aphyllanthe.fr\/association\/pdf\/statuts-v5.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">nouveaux statuts<\/a> \u00e0 l\u2019unanimit\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/AG-rapport-moral-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-9301\" srcset=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/AG-rapport-moral-300x225.jpg 300w, https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/AG-rapport-moral.jpg 577w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>La pr\u00e9sidente Claude Huguet-Bordel a ouvert l\u2019AG Ordinaire en pr\u00e9sentant le <a href=\"http:\/\/www.aphyllanthe.fr\/association\/pdf\/rapport-moral-ag\/rapport-ag-2019.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">rapport moral de 2018<\/a>, ann\u00e9e marqu\u00e9e par le d\u00e9m\u00e9nagement de la biblioth\u00e8que dans des locaux temporaires, la d\u00e9localisation de plusieurs activit\u00e9s vers les communes voisines et le d\u00e9but du programme \u201cpartage de savoirs\u201d. Claude a aussi remerci\u00e9 tous les partenaires, les adh\u00e9rents, les b\u00e9n\u00e9voles et les membres du CA pour leurs actions en faveur de l\u2019Association en 2018. Par la suite le tr\u00e9sorier Yves a pr\u00e9sent\u00e9 le r\u00e9sultat financier de 2018, ann\u00e9e de gestion serr\u00e9e des d\u00e9penses (sans toutefois baisser le rythme des activit\u00e9s) afin de retrouver une tr\u00e9sorerie raisonnable.<\/p>\n<p>Mis au vote, ces deux rapports ont \u00e9t\u00e9 approuv\u00e9s \u00e0 l\u2019unanimit\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/AG-2019-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-9302\" srcset=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/AG-2019-300x225.jpg 300w, https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/AG-2019.jpg 577w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Lors de l\u2019\u00e9lection du CA, onze des douze membres du C.A 2018 sortant se pr\u00e9sentaient \u00e0 nouveau. M Daniel Viard, s\u2019est propos\u00e9 comme 12\u00e8me membre du <a href=\"https:\/\/www.aphyllanthe.fr\/association\/accueil\/ca-et-ag\/\">C.A 2019<\/a> et, lors du vote, l\u2019assembl\u00e9e a approuv\u00e9 ce nouveau conseil \u00e0 l\u2019unanimit\u00e9.<\/p>\n<p>Pour clore l\u2019AG Ordinaire, la pr\u00e9sidente a propos\u00e9 un d\u00e9bat-\u00e9change d\u2019id\u00e9es sur l\u2019 orientation future de l\u2019Association. Plusieurs sujets \u00e9taient abord\u00e9s par les adh\u00e9rents:<\/p>\n<ul>\n<li>programmer des rencontres autour des nouveaux jeux de soci\u00e9t\u00e9 pour f\u00e9d\u00e9rer un nouveau public de jeunes et adultes,<\/li>\n<li>faire \u00e9voluer le programme de partage de savoirs au del\u00e0 des m\u00e9tiers artistiques vers (par exemple), le bricolage, le jardinage, &#8230;<\/li>\n<li>prendre des initiatives sur le th\u00e8me de l\u2019\u00e9co-responsabilit\u00e9,<\/li>\n<li>utiliser \u00e0 bon escient des nouveaux locaux \u00e0 partir de septembre 2019 (caf\u00e9 de village, expositions ?)<\/li>\n<\/ul>\n<p>La soir\u00e9e s\u2019est termin\u00e9e avec un buffet-repas collaboratif tr\u00e8s convivial et gourmand.<br \/>\n<div id='gallery-1' class='gallery galleryid-9292 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/buffet-AG-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/buffet-AG-169x300.jpg 169w, https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/buffet-AG.jpg 512w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/table-AG-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/table-AG-169x300.jpg 169w, https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/table-AG.jpg 512w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"169\" height=\"300\" src=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/Table-repas-AG-169x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/Table-repas-AG-169x300.jpg 169w, https:\/\/www.aphyllanthe.fr\/association\/wp-content\/uploads\/2019\/03\/Table-repas-AG.jpg 512w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Assembl\u00e9e G\u00e9n\u00e9rale Annuelle de l&rsquo;Association l\u2019Aphyllanthe s\u2019est d\u00e9roul\u00e9e le vendredi 15 mars \u00e0 18H30 \u00e0 la salle polyvalente de Foissac en pr\u00e9sence d&rsquo;une soixantaine d&rsquo;adh\u00e9rents.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-9292","post","type-post","status-publish","format-standard","hentry","category-reportage"],"_links":{"self":[{"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/posts\/9292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/comments?post=9292"}],"version-history":[{"count":0,"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/posts\/9292\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/media?parent=9292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/categories?post=9292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.aphyllanthe.fr\/association\/wp-json\/wp\/v2\/tags?post=9292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}